{"id":3253,"date":"2020-04-30T12:56:54","date_gmt":"2020-04-30T12:56:54","guid":{"rendered":"https:\/\/www.lebenlernen.com\/sek_schoenebeck\/?p=3253"},"modified":"2025-02-03T16:09:22","modified_gmt":"2025-02-03T16:09:22","slug":"neustart","status":"publish","type":"post","link":"https:\/\/www.lebenlernen.com\/sek_schoenebeck\/neustart\/","title":{"rendered":"Neustart"},"content":{"rendered":"\n<p>Liebe Eltern, liebe Sch\u00fcler*innen,<\/p>\n\n\n\n<p>es geht wieder los. In den kommenden Wochen wird die Schulschlie\u00dfung Schritt f\u00fcr Schritt aufgehoben.<\/p>\n\n\n\n<p>Genaue Informationen zur weiteren Verfahrensweise erhalten Sie in den n\u00e4chsten Tagen und Wochen per Mail. Bitte pr\u00fcfen Sie regelm\u00e4\u00dfig Ihre Postf\u00e4cher.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liebe Eltern, liebe Sch\u00fcler*innen, es geht wieder los. In den kommenden Wochen wird die Schulschlie\u00dfung Schritt f\u00fcr Schritt aufgehoben. Genaue Informationen zur weiteren Verfahrensweise erhalten Sie in den n\u00e4chsten Tagen und Wochen per Mail. Bitte pr\u00fcfen Sie regelm\u00e4\u00dfig Ihre Postf\u00e4cher.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-3253","post","type-post","status-publish","format-standard","hentry","category-2019-2020"],"_links":{"self":[{"href":"https:\/\/www.lebenlernen.com\/sek_schoenebeck\/wp-json\/wp\/v2\/posts\/3253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lebenlernen.com\/sek_schoenebeck\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lebenlernen.com\/sek_schoenebeck\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lebenlernen.com\/sek_schoenebeck\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lebenlernen.com\/sek_schoenebeck\/wp-json\/wp\/v2\/comments?post=3253"}],"version-history":[{"count":1,"href":"https:\/\/www.lebenlernen.com\/sek_schoenebeck\/wp-json\/wp\/v2\/posts\/3253\/revisions"}],"predecessor-version":[{"id":4360,"href":"https:\/\/www.lebenlernen.com\/sek_schoenebeck\/wp-json\/wp\/v2\/posts\/3253\/revisions\/4360"}],"wp:attachment":[{"href":"https:\/\/www.lebenlernen.com\/sek_schoenebeck\/wp-json\/wp\/v2\/media?parent=3253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lebenlernen.com\/sek_schoenebeck\/wp-json\/wp\/v2\/categories?post=3253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lebenlernen.com\/sek_schoenebeck\/wp-json\/wp\/v2\/tags?post=3253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}