{"id":2938,"date":"2020-03-15T15:58:21","date_gmt":"2020-03-15T15:58:21","guid":{"rendered":"https:\/\/www.lebenlernen.com\/sek_schoenebeck\/?p=2938"},"modified":"2025-02-03T16:09:25","modified_gmt":"2025-02-03T16:09:25","slug":"aufgaben-waehrend-der-schulschliessung","status":"publish","type":"post","link":"https:\/\/www.lebenlernen.com\/sek_schoenebeck\/aufgaben-waehrend-der-schulschliessung\/","title":{"rendered":"Aufgaben w\u00e4hrend der Schulschlie\u00dfung"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\"><strong>&gt;&gt;&gt;Pr\u00fcfungen werden verschoben&lt;&lt;&lt;<\/strong><\/h4>\n\n\n\n<p><strong>Die Pr\u00fcfungen f\u00fcr den Realschulabschluss werden in Sachsen-Anhalt verschoben.<\/strong><\/p>\n\n\n\n<p><strong>Die schriftliche Pr\u00fcfung im Fach Deutsch ist nun am 11. Mai, im Fach Englisch am 13. Mai und im Fach Mathematik am 15. Mai 2020.<\/strong><\/p>\n\n\n\n<p><strong>Der Zukunftstag am 26.03.2020 entf\u00e4llt.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Liebe Eltern, liebe Sch\u00fcler,<\/p>\n\n\n\n<p>vom 16.03.-14.04.2020 bleiben alle Schulen im Land Sachsen-Anhalt geschlossen. <\/p>\n\n\n\n<p>Die Schule hat nun Aufgaben ver\u00f6ffentlicht, die von allen Sch\u00fclern bearbeitet werden m\u00fcssen. <\/p>\n\n\n\n<p>Diese Aufgaben sind auf der folgenden Seite zu finden: <a href=\"https:\/\/www.lebenlernen.com\/sek_schoenebeck\/aufgaben\/\">https:\/\/www.lebenlernen.com\/sek_schoenebeck\/aufgaben\/<\/a><\/p>\n\n\n\n<p>Liebe Sch\u00fcler, informiert euch regelm\u00e4\u00dfig \u00fcber eventuelle Aktualisierungen der Arbeitsauftr\u00e4ge. <\/p>\n\n\n\n<p>Wir werden versuchen, wichtige Informationen m\u00f6glichst schnell \u00fcber die Homepage und \u00fcber die Elternvertreter der Klassen weiterzuleiten. <\/p>\n\n\n\n<p>Bleiben Sie gesund.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Das Team der Sekundarschule LebenLernen<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&gt;&gt;&gt;Pr\u00fcfungen werden verschoben&lt;&lt;&lt; Die Pr\u00fcfungen f\u00fcr den Realschulabschluss werden in Sachsen-Anhalt verschoben. Die schriftliche Pr\u00fcfung im Fach Deutsch ist nun am 11. Mai, im Fach Englisch am 13. Mai und im Fach Mathematik am 15. Mai 2020. Der Zukunftstag am 26.03.2020 entf\u00e4llt. Liebe Eltern, liebe Sch\u00fcler, vom 16.03.-14.04.2020 bleiben alle Schulen im Land Sachsen-Anhalt geschlossen.<\/p>\n<div><a class=\"btn-filled btn\" href=\"https:\/\/www.lebenlernen.com\/sek_schoenebeck\/aufgaben-waehrend-der-schulschliessung\/\" title=\"Aufgaben w\u00e4hrend der Schulschlie\u00dfung\">Read More<\/a><\/div>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-2938","post","type-post","status-publish","format-standard","hentry","category-2019-2020"],"_links":{"self":[{"href":"https:\/\/www.lebenlernen.com\/sek_schoenebeck\/wp-json\/wp\/v2\/posts\/2938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lebenlernen.com\/sek_schoenebeck\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lebenlernen.com\/sek_schoenebeck\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lebenlernen.com\/sek_schoenebeck\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lebenlernen.com\/sek_schoenebeck\/wp-json\/wp\/v2\/comments?post=2938"}],"version-history":[{"count":1,"href":"https:\/\/www.lebenlernen.com\/sek_schoenebeck\/wp-json\/wp\/v2\/posts\/2938\/revisions"}],"predecessor-version":[{"id":4365,"href":"https:\/\/www.lebenlernen.com\/sek_schoenebeck\/wp-json\/wp\/v2\/posts\/2938\/revisions\/4365"}],"wp:attachment":[{"href":"https:\/\/www.lebenlernen.com\/sek_schoenebeck\/wp-json\/wp\/v2\/media?parent=2938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lebenlernen.com\/sek_schoenebeck\/wp-json\/wp\/v2\/categories?post=2938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lebenlernen.com\/sek_schoenebeck\/wp-json\/wp\/v2\/tags?post=2938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}