{"id":2096,"date":"2015-09-18T06:24:08","date_gmt":"2015-09-18T06:24:08","guid":{"rendered":"http:\/\/www.lebenlernen.com\/rs_braunschweig\/?p=2096"},"modified":"2015-09-18T06:25:31","modified_gmt":"2015-09-18T06:25:31","slug":"sportspieletag-05-09-2015","status":"publish","type":"post","link":"https:\/\/www.lebenlernen.com\/rs_braunschweig\/sportspieletag-05-09-2015\/","title":{"rendered":"Sportspieletag 05.09.2015"},"content":{"rendered":"<p style=\"text-align: left;\">Am Freitag, den 05.09.2015 fand an unserer Schule das Sportspielefest zum Schuljahresbeginn statt.<\/p>\n<p>Dieses Jahr war das Motto \u201eWasser marsch!\u201c und so hatten unsere Sch\u00fclerinnen und Sch\u00fcler die etwas ungew\u00f6hnlichen Aufgaben zu absolvieren.<\/p>\n<p>Es wurde z.B. ein Staffellauf mit Feuerwehrschutzkleidung absolviert. Dabei mussten die Kleidungsst\u00fccke wie ein Staffelstab an die n\u00e4chsten L\u00e4ufer der Gruppe \u00fcbergeben und von diesen angezogen werden.<\/p>\n<p><a href=\"https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-content\/uploads\/2015\/07\/feuerwehrlauf.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2086\" src=\"https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-content\/uploads\/2015\/07\/feuerwehrlauf-169x300.jpg\" alt=\"METADATA-START\" width=\"150\" height=\"266\" srcset=\"https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-content\/uploads\/2015\/07\/feuerwehrlauf-169x300.jpg 169w, https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-content\/uploads\/2015\/07\/feuerwehrlauf-31x55.jpg 31w, https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-content\/uploads\/2015\/07\/feuerwehrlauf.jpg 252w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/p>\n<p>In der Sporthalle gab es einen \u201egef\u00e4hrlichen\u201c Hindernisparcours, auf den sich sogar der eine oder andere Coach wagte.<\/p>\n<p>Eine weitere Aufgabe war au\u00dferdem, das Erlernen verschiedener Feuerwehrknoten und eine Geschicklichkeits\u00fcbung die \u201eblindes Vertrauen\u201c erforderte.<\/p>\n<p>Abschlie\u00dfend musste das sportliche Geschick bewiesen werden, indem eine Schlauchleitung aus 6 C-Schl\u00e4uchen gemeinsam ausgelegt und wieder aufgerollt werden musste.<\/p>\n<p><a href=\"https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-content\/uploads\/2015\/07\/20150904_100616.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2080\" src=\"https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-content\/uploads\/2015\/07\/20150904_100616-300x169.jpg\" alt=\"METADATA-START\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-content\/uploads\/2015\/07\/20150904_100616-300x169.jpg 300w, https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-content\/uploads\/2015\/07\/20150904_100616-98x55.jpg 98w, https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-content\/uploads\/2015\/07\/20150904_100616.jpg 448w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-content\/uploads\/2015\/07\/20150904_102420.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2079\" src=\"https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-content\/uploads\/2015\/07\/20150904_102420-300x169.jpg\" alt=\"METADATA-START\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-content\/uploads\/2015\/07\/20150904_102420-300x169.jpg 300w, https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-content\/uploads\/2015\/07\/20150904_102420-98x55.jpg 98w, https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-content\/uploads\/2015\/07\/20150904_102420.jpg 448w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-content\/uploads\/2015\/07\/20150904_101005.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-2078\" src=\"https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-content\/uploads\/2015\/07\/20150904_101005-300x169.jpg\" alt=\"METADATA-START\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-content\/uploads\/2015\/07\/20150904_101005-300x169.jpg 300w, https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-content\/uploads\/2015\/07\/20150904_101005-98x55.jpg 98w, https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-content\/uploads\/2015\/07\/20150904_101005.jpg 448w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am Freitag, den 05.09.2015 fand an unserer Schule das Sportspielefest zum Schuljahresbeginn statt. Dieses Jahr war das Motto \u201eWasser marsch!\u201c und so hatten unsere Sch\u00fclerinnen und Sch\u00fcler die etwas ungew\u00f6hnlichen Aufgaben zu absolvieren. Es wurde z.B. ein Staffellauf mit Feuerwehrschutzkleidung absolviert. Dabei mussten die Kleidungsst\u00fccke wie ein Staffelstab an die n\u00e4chsten L\u00e4ufer der Gruppe \u00fcbergeben<\/p>\n<div><a class=\"btn-filled btn\" href=\"https:\/\/www.lebenlernen.com\/rs_braunschweig\/sportspieletag-05-09-2015\/\" title=\"Sportspieletag 05.09.2015\">Read More<\/a><\/div>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2096","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-json\/wp\/v2\/posts\/2096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-json\/wp\/v2\/comments?post=2096"}],"version-history":[{"count":0,"href":"https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-json\/wp\/v2\/posts\/2096\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-json\/wp\/v2\/media?parent=2096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-json\/wp\/v2\/categories?post=2096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lebenlernen.com\/rs_braunschweig\/wp-json\/wp\/v2\/tags?post=2096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}